{"id":29315,"date":"2024-11-25T10:42:50","date_gmt":"2024-11-25T10:42:50","guid":{"rendered":"https:\/\/www.speedmodels.ch\/produkte\/non class\u00e9\/profile-en-plastique-carre-plein-35-mm\/"},"modified":"2024-11-25T10:42:50","modified_gmt":"2024-11-25T10:42:50","slug":"profile-en-plastique-carre-plein-35-mm","status":"publish","type":"product","link":"https:\/\/www.speedmodels.ch\/fr\/produits\/profiles-plaques\/profiles-en-plastic\/profil-en-plastique-rectangulaire\/profile-en-plastique-carre-plein-35-mm\/","title":{"rendered":"Profile en plastique carr\u00e9 plein 3,5 mm"},"content":{"rendered":"<p><strong>Profile en plastique de Raboesch carr\u00e9 plein<\/strong><\/p>\n<p>materiaux: ASA (blanc)<\/p>\n<p>A = 3,5 mm<\/p>\n<p>B = 3,5 mm<\/p>\n<p>longueur: 1000 mm<\/p>\n<p>Caract\u00e9ristiques: tr\u00e8s r\u00e9sistant aux chocs &#8211; haute r\u00e9sistance aux intemp\u00e9ries et aux UV &#8211; grande rigidit\u00e9 &#8211; facile \u00e0 vernir et \u00e0 peindre &#8211; facile \u00e0 coller (par exemple Plasti-ZAP, ZAP A GAP, Uhu-Plast etc.). Particuli\u00e8rement adapt\u00e9 \u00e0 la construction de mod\u00e8les architecturaux, ferroviaires, navals et automobiles etc.<\/p>\n<div style=\"text-align:left\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a href=\"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product\/29315\/?action=genpdf&amp;id=29315\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/speedmodels.ch\/wp-content\/uploads\/2021\/09\/pdf_icon.png\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Profile en plastique de Raboesch carr\u00e9 plein materiaux: ASA (blanc) A = 3,5 mm B = 3,5 mm longueur: 1000 mm Caract\u00e9ristiques: tr\u00e8s r\u00e9sistant aux chocs &#8211; haute r\u00e9sistance aux intemp\u00e9ries et aux UV &#8211; grande rigidit\u00e9 &#8211; facile \u00e0 vernir et \u00e0 peindre &#8211; facile \u00e0 coller (par exemple Plasti-ZAP, ZAP A GAP, Uhu-Plast [&hellip;]<\/p>\n","protected":false},"featured_media":10102,"template":"","meta":[],"product_brand":[],"product_cat":[1798,1512,1782],"product_tag":[],"class_list":["post-29315","product","type-product","status-publish","has-post-thumbnail","product_cat-profil-en-plastique-rectangulaire","product_cat-profiles-plaques","product_cat-profiles-en-plastic","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product\/29315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product\/29315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/media\/10102"}],"wp:attachment":[{"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/media?parent=29315"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=29315"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=29315"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=29315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}