{"id":19255,"date":"2022-10-13T13:06:34","date_gmt":"2022-10-13T13:06:34","guid":{"rendered":"https:\/\/www.speedmodels.ch\/produkte\/unkategorisiert\/helice-cam-carbon-light-s-11-x-5-gauche\/"},"modified":"2024-02-08T14:49:23","modified_gmt":"2024-02-08T14:49:23","slug":"helice-cam-carbon-light-s-11-x-5-gauche","status":"publish","type":"product","link":"https:\/\/www.speedmodels.ch\/fr\/produits\/accessoires\/pour-avions\/helice\/helice-rigide\/helice-cam-carbon-light-s-11-x-5-gauche\/","title":{"rendered":"H\u00e9lice CAM Carbon Light-S 11 x 5&Prime; Gauche"},"content":{"rendered":"<p>H\u00e9lice CAMcarbon Light Prop<\/p>\n<p>Cette s\u00e9rie d&rsquo;h\u00e9lices est con\u00e7ue pour les entra\u00eenements \u00e9lectriques et a \u00e9t\u00e9 sp\u00e9cialement calcul\u00e9e pour une pouss\u00e9e \u00e9lev\u00e9e m\u00eame \u00e0 basse vitesse. Pour ce faire, un profil mince avec une plus grande profondeur a \u00e9t\u00e9 utilis\u00e9. Avec cette s\u00e9rie, une h\u00e9lice l\u00e9g\u00e8re, stable et r\u00e9sistante \u00e0 la torsion, renforc\u00e9e de carbone, a \u00e9t\u00e9 cr\u00e9e. Les h\u00e9lices sont particuli\u00e8rement adapt\u00e9es aux mod\u00e8les multicopt\u00e8res et peuvent parfois aussi \u00eatre utilis\u00e9es par paires (sens antihoraire et horaire).<\/p>\n<p>Le d\u00e9veloppement a \u00e9t\u00e9 effectu\u00e9 sur un syst\u00e8me CAO afin d&rsquo;assurer un d\u00e9grad\u00e9 et une forme de profil exacts. La forme des pales est identique \u00e0 nos h\u00e9lices pliantes en carbone Cam \u00e9prouv\u00e9es, mais avec un moyeu plus petit et donc plus l\u00e9ger. Les moules, qui sont fabriqu\u00e9s \u00e0 l&rsquo;aide de la technologie CNC, et les h\u00e9lices renforc\u00e9es de fibres de carbone sont fabriqu\u00e9s exclusivement en Allemagne.<\/p>\n<p>Cette version sp\u00e9ciale dispose d&rsquo;un <strong>filetage M6<\/strong> int\u00e9gr\u00e9, avec lequel elle peut \u00eatre viss\u00e9e directement sur les moteurs avec un filetage d&rsquo;arbre <strong>M6<\/strong>. Par exemple, ces h\u00e9lices peuvent \u00eatre viss\u00e9es directement sur le DJI Phantom.<\/p>\n<p>Tours max 14&rsquo;000 t\/min.<\/p>\n<div style=\"text-align:left\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a href=\"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product\/19255\/?action=genpdf&amp;id=19255\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/speedmodels.ch\/wp-content\/uploads\/2021\/09\/pdf_icon.png\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>H\u00e9lice CAMcarbon Light Prop Cette s\u00e9rie d&rsquo;h\u00e9lices est con\u00e7ue pour les entra\u00eenements \u00e9lectriques et a \u00e9t\u00e9 sp\u00e9cialement calcul\u00e9e pour une pouss\u00e9e \u00e9lev\u00e9e m\u00eame \u00e0 basse vitesse. Pour ce faire, un profil mince avec une plus grande profondeur a \u00e9t\u00e9 utilis\u00e9. Avec cette s\u00e9rie, une h\u00e9lice l\u00e9g\u00e8re, stable et r\u00e9sistante \u00e0 la torsion, renforc\u00e9e de carbone, [&hellip;]<\/p>\n","protected":false},"featured_media":15265,"template":"","meta":[],"product_brand":[],"product_cat":[1518,1588,1589,1519],"product_tag":[],"class_list":["post-19255","product","type-product","status-publish","has-post-thumbnail","product_cat-accessoires","product_cat-helice","product_cat-helice-rigide","product_cat-pour-avions","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product\/19255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product\/19255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/media\/15265"}],"wp:attachment":[{"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/media?parent=19255"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=19255"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=19255"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.speedmodels.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=19255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}